{"id":2365,"date":"2021-08-09T18:31:56","date_gmt":"2021-08-09T21:31:56","guid":{"rendered":"https:\/\/www.comunidadeativa.jor.br\/?p=2365"},"modified":"2021-08-09T18:37:10","modified_gmt":"2021-08-09T21:37:10","slug":"2365","status":"publish","type":"post","link":"https:\/\/www.comunidadeativa.jor.br\/index.php\/2021\/08\/09\/2365\/","title":{"rendered":"Ebook com receitas do &#8220;Territ\u00f3rios e Redes Criativas &#8211; Etapa Lagoinha&#8221; j\u00e1 est\u00e1 dispon\u00edvel"},"content":{"rendered":"<p>Ningu\u00e9m tem d\u00favidas de que a comida de boteco tem um lugar especial na gastronomia belo-horizontina. Com uma diversidade que \u00e9 capaz de agradar os mais variados gostos, ela j\u00e1 se estabeleceu como uma refer\u00eancia da culin\u00e1ria de BH.<\/p>\n<p>Dentro desse universo que desafia o paladar, h\u00e1 espa\u00e7os bem definidos, que s\u00e3o identificados por uma cozinha que n\u00e3o se diferencia tanto pela inova\u00e7\u00e3o. Ao contr\u00e1rio, em um tempo em que tudo \u00e9 \u201cgourmetizado\u201d, ela estabelece o seu diferencial justamente por manter as tradi\u00e7\u00f5es de uma culin\u00e1ria sem tanta sofistica\u00e7\u00e3o, mas que nos leva a sabores que ficam marcados na mem\u00f3ria.<\/p>\n<p>Entre elas est\u00e1 a culin\u00e1ria de bares da Lagoinha, que agora t\u00eam uma amostra apresentada em um ebook, j\u00e1 dispon\u00edvel para download.<\/p>\n<h5>Boteco da Lagoinha<\/h5>\n<p>Bons exemplos de pratos com com \u00f3tima qualidade podem ser degustados nos 12 estabelecimentos da regi\u00e3o da Lagoinha, que foram selecionados pelo projeto <em>Territ\u00f3rios e Redes Criativas &#8211; Etapa Lagoinha<\/em>, realizado pela Belotur e pelo Sebrae Minas em parceria com o Senac. Com a curadoria do jornalista Daniel Neto \u2014 o Nenel, do Blog Baixa Gastronomia \u2014 e da chefe de cozinha Mariana Gontijo, que \u00e9 pesquisadora da gastronomia mineira, a iniciativa permitiu que fossem levantados e mapeados os botecos e restaurantes da regi\u00e3o, que tamb\u00e9m receberam capacita\u00e7\u00f5es e consultorias personalizadas para os empreendimentos.<\/p>\n<p>O resultado foi a publica\u00e7\u00e3o de um ebook que tem o mesmo nome do projeto, que ser\u00e1 lan\u00e7ado nessa ter\u00e7a-feira, dia 10, por meio de uma live gerada do bar \u201cVenda da Esquina\u201d \u2014 a partir das 19h no <a href=\"http:\/\/www.youtube.com\/sebraeminas\" target=\"_blank\" rel=\"noopener\">Youtube do Sebrae<\/a>. Por\u00e9m, se voc\u00ea quiser, j\u00e1 pode baixar a publica\u00e7\u00e3o (<a href=\"http:\/\/portalbelohorizonte.com.br\/creativecity\/gastronomia\/downloads\" target=\"_blank\" rel=\"noopener\">clique aqui<\/a>), que conta com receitas que s\u00f3 os bons botequins s\u00e3o capazes de reproduzir.<\/p>\n<h5>Degusta\u00e7\u00e3o e capacita\u00e7\u00e3o<\/h5>\n<p>O projeto foi executado em duas frentes. Por um lado, Nenel se ocupava de degustar os pratos e descrev\u00ea-los em suas publica\u00e7\u00f5es nas redes sociais. Ao mesmo tempo, Mariana apoiava os propriet\u00e1rios dos estabelecimentos, sugerindo formas de apresenta\u00e7\u00e3o dos pratos, de c\u00e1lculo de custos e de pre\u00e7os finais, da apresenta\u00e7\u00e3o ao cliente e at\u00e9 no arranjo das mesas e dos balc\u00f5es e dos restaurantes.<\/p>\n<p>Assim, foi poss\u00edvel criar uma din\u00e2mica gastron\u00f4mica diferenciada em uma regi\u00e3o tradicional de BH. Esta experi\u00eancia ser\u00e1 contada na live por Nenel e Mariana, que tamb\u00e9m v\u00e3o conversar com C\u00e1tia C\u00e2ndida, da Venda da Esquina, e com Marcos Boffa, diretor de Pol\u00edticas de Turismo e Inova\u00e7\u00e3o da Belotur, e Ricardo Lana, analista do Sebrae Minas.<\/p>\n<p>A live tamb\u00e9m servir\u00e1 para o coment\u00e1rio sobre receitas que ser\u00e3o degustadas durante o evento e sobre as hist\u00f3rias e as tradi\u00e7\u00f5es da Lagoinha.<\/p>\n<h5>O projeto<\/h5>\n<p>O <em>Territ\u00f3rios e Redes Criativas<\/em> foi lan\u00e7ado em dezembro de 2019 com a proposta de valoriza\u00e7\u00e3o da cultura material e imaterial de algumas regi\u00f5es de BH, visando com isso estimular produ\u00e7\u00f5es locais dos v\u00e1rios segmentos da economia criativa, potencializando e dando mais visibilidade aos empreendedores locais e criando novas oportunidades de emprego e renda. Para a Lagoinha foi escolhido o segmento da gastronomia, que est\u00e1 vinculado ao processo hist\u00f3rico de constitui\u00e7\u00e3o e de ocupa\u00e7\u00e3o da regi\u00e3o.<\/p>\n<p>No ano passado foram os empreendimentos locais foram pesquisados e mapeados, o que permitiu compreender demandas e adequar a\u00e7\u00f5es a elas.\u00a0Nesta fase, a pesquisa <em>Prim\u00f3rdios da Cozinha Mineira<\/em>, realizada pelo Senac, buscou identificar por meio da hist\u00f3ria oral as ra\u00edzes indenit\u00e1rias da gastronomia da regi\u00e3o, verificando tamb\u00e9m as m\u00faltiplas influ\u00eancias culturais que colaboraram para a seu surgimento.<\/p>\n<p>O Sebrae Minas, por sua vez, mapeou os estabelecimentos de gastronomia com a finalidade de entender as dificuldades e desafios que os pequenos empreendedores locais est\u00e3o enfrentando, buscando tamb\u00e9m apontar poss\u00edveis solu\u00e7\u00f5es para tornar os empreendimentos mais competitivos. Os resultados apontados em ambas as pesquisas subsidiaram o processo de capacita\u00e7\u00e3o realizado na etapa seguinte.<\/p>\n<p>Iniciada em setembro de 2020, a segunda fase do projeto realizou uma s\u00e9rie de capacita\u00e7\u00f5es e consultorias personalizadas, que se seguiram at\u00e9 dezembro. Ao longo do processo formativo, foram realizadas oficinas e consultorias individualizadas, que somaram mais de 30 horas de aten\u00e7\u00e3o aos empreendedores.<\/p>\n<h5>O ebook<\/h5>\n<p>Al\u00e9m das inten\u00e7\u00f5es dos realizadores do projeto, o ebook tamb\u00e9m apresenta brevemente cada um dos 12 estabelecimentos que fizeram parte da pesquisa e que brindaram o leitor com uma de suas receitas de maior destaque. Entre elas, \u00e9 poss\u00edvel encontrar uma deliciosa feijoada de feij\u00e3o branco, a tradicional esfiha de boteco e uma conserva de jil\u00f3 que s\u00f3 os bares mais tradicionais servem. Ainda, \u00e9 claro, n\u00e3o falta a boa carne cozida, o joelho de porco e at\u00e9 uma farofa de fub\u00e1 torrado que repete uma receita de fam\u00edlia.<\/p>\n<p>Ent\u00e3o, para levar um pouco da Lagoinha pra dentro de casa, \u00e9 s\u00f3 baixar o ebook, colocar a cozinha para funcionar, reproduzir as receitas e abrir aquela cervejinha gelada. Bom apetite!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ningu\u00e9m tem d\u00favidas de que a comida de boteco tem um lugar especial na gastronomia belo-horizontina. Com uma diversidade que<\/p>\n","protected":false},"author":1,"featured_media":2366,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/comments?post=2365"}],"version-history":[{"count":5,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2365\/revisions"}],"predecessor-version":[{"id":2372,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2365\/revisions\/2372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/media\/2366"}],"wp:attachment":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/media?parent=2365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/categories?post=2365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/tags?post=2365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}