{"id":2506,"date":"2021-09-21T10:04:03","date_gmt":"2021-09-21T13:04:03","guid":{"rendered":"https:\/\/www.comunidadeativa.jor.br\/?p=2506"},"modified":"2021-09-22T15:42:42","modified_gmt":"2021-09-22T18:42:42","slug":"de-uma-padaria-da-antiga-pompeia-uma-reflexao-de-felicidade-para-tempos-de-pandemia","status":"publish","type":"post","link":"https:\/\/www.comunidadeativa.jor.br\/index.php\/2021\/09\/21\/de-uma-padaria-da-antiga-pompeia-uma-reflexao-de-felicidade-para-tempos-de-pandemia\/","title":{"rendered":"De uma padaria da antiga Pompeia, uma reflex\u00e3o de felicidade para tempos de pandemia"},"content":{"rendered":"<p>A felicidade humana \u00e9 notadamente resistente. Esta foi uma das principais li\u00e7\u00f5es que os pesquisadores respons\u00e1veis pela elabora\u00e7\u00e3o do <a href=\"https:\/\/happiness-report.s3.amazonaws.com\/2021\/WHR+21.pdf\" target=\"_blank\" rel=\"noopener\">Relat\u00f3rio Mundial da Felicidade 2021<\/a> obtiveram ap\u00f3s entrevistarem 100 mil pessoas em 95 pa\u00edses em 2020. A avalia\u00e7\u00e3o considerou temas relacionados ao apoio social que os entrevistados recebem, ao rendimento, \u00e0 qualidade e expectativa de vida, \u00e0 liberdade, \u00e0 generosidade e \u00e0 exist\u00eancia ou n\u00e3o de corrup\u00e7\u00e3o no lugar onde vivem.<\/p>\n<p>Por incr\u00edvel que pare\u00e7a, mesmo com a pandemia, o \u00edndice de felicidade manteve-se mundialmente est\u00e1vel no ano passado, com rela\u00e7\u00e3o a 2019. Seguida de perto pela Dinamarca e pela Su\u00ed\u00e7a, pelo quarto ano consecutivo, a Finl\u00e2ndia figurou em primeiro lugar no ranking da felicidade, marcando 7,889 pontos, em uma escala de 0 a 10.<\/p>\n<p>Destoando da m\u00e9dia mundial, o Brasil amarga uma 41\u00aa coloca\u00e7\u00e3o, com pontua\u00e7\u00e3o 6,11, a pior desde o in\u00edcio da apura\u00e7\u00e3o em 2005. A melhor pontua\u00e7\u00e3o j\u00e1 alcan\u00e7ada pelo pa\u00eds foi 7,14, anotada em 2013. O pa\u00eds mais infeliz do mundo entre os pesquisados foi o Zimbabwe, que marcou apenas 3,299 pontos.<\/p>\n<p>Por\u00e9m, considerando a situa\u00e7\u00e3o global, os pesquisadores perceberam que a resili\u00eancia prevaleceu, contribuindo para que grande parte das pessoas n\u00e3o piorasse a sensa\u00e7\u00e3o de felicidade, mesmo diante de todas as dificuldades que estamos enfrentando.<\/p>\n<h5>Inscri\u00e7\u00e3o de padaria<\/h5>\n<p><a href=\"https:\/\/en.wikipedia.org\/wiki\/Felicitas#\/media\/File:Bible_Museum_-_Bordellzeichen.jpg\"><em>Hic habitat felicitas<\/em><\/a>\u00a0(<em>Aqui mora a felicidade<\/em>) diz a inscri\u00e7\u00e3o encontrada em uma padaria de Pompeia, a cidade romana que foi arrasada pela <a href=\"https:\/\/www.nationalgeographic.com\/science\/article\/vesuvius-baked-people-turned-brain-to-glass\">erup\u00e7\u00e3o do Ves\u00favio<\/a>, em 79 dC, que serviu como ponto de partida para que a professora de Hist\u00f3ria Nadejda Willians, da Universidade de West Virg\u00ednia, nos Estados Unidos, fizesse uma an\u00e1lise sobre a felicidade no <a href=\"https:\/\/theconversation.com\/what-a-baker-from-ancient-pompeii-can-teach-us-about-happiness-166010\" target=\"_blank\" rel=\"noopener\">The Conversation<\/a>.<\/p>\n<p>Nadejda destaca que Felicitas e Fortuna, duas deusas pr\u00f3ximas em atributos, eram veneradas em Roma com a expectativa de que alguma interven\u00e7\u00e3o das divindades favorecesse a vida dos seguidores. Portanto, a professora entende que, ao associar a felicidade (\u201cfelicitas\u201d) ao pr\u00f3prio estabelecimento, afirmando que ali era a sua morada, o padeiro de Pomp\u00e9ia talvez estivesse manifestando o desejo de atrair as b\u00ean\u00e7\u00e3os para seu neg\u00f3cio e para sua vida.<\/p>\n<p>A acad\u00eamica explica ainda que a felicidade tamb\u00e9m era associada ao dinheiro e ao poder, aparecendo, inclusive, em cunhagens de moedas. \u201cMas, al\u00e9m dessa vis\u00e3o do dinheiro e do poder como fonte de felicidade, havia uma ironia cruel. Felicitas e Felix eram nomes comumente usados \u200b\u200bpara escravos femininos e masculinos. Por exemplo,\u00a0<a href=\"https:\/\/www.livius.org\/articles\/person\/antonius-felix\/\">Antonius Felix<\/a>\u00a0, o governador da Jud\u00e9ia no primeiro s\u00e9culo, era um ex-escravo, enquanto Felicitas era o nome da mulher escravizada que ficou\u00a0<a href=\"https:\/\/sourcebooks.fordham.edu\/source\/perpetua.asp\">famosa ao ser martirizada junto Perp\u00e9tua<\/a>\u00a0em 203 dC\u201d, revela.<\/p>\n<h5>Mas, onde, de fato, mora a felicidade?<\/h5>\n<p>\u201cNa sociedade de hoje, a felicidade pode existir apenas \u00e0s custas de outra pessoa?\u00a0Onde fica a felicidade, \u00e0 medida que as\u00a0<a href=\"https:\/\/mhanational.org\/issues\/state-mental-health-america\">taxas de depress\u00e3o e outras doen\u00e7as mentais<\/a>\u00a0aumentam e os dias de trabalho aumentam?\u201d, questiona Nadejda.<\/p>\n<p>Pesquisas revelam que, <a href=\"https:\/\/20somethingfinance.com\/american-hours-worked-productivity-vacation\/\">nas \u00faltimas duas d\u00e9cadas<\/a>, os trabalhadores americanos aumentaram a carga de trabalho. Uma\u00a0<a href=\"https:\/\/www.bostonglobe.com\/2021\/08\/19\/magazine\/busting-work-family-myth-turns-out-your-job-doesnt-have-be-your-life\/\">pesquisa Gallup de 2020<\/a>\u00a0descobriu que 44% dos funcion\u00e1rios em tempo integral trabalhavam mais de 45 horas por semana, enquanto 17% das pessoas trabalhavam 60 ou mais horas semanais.<\/p>\n<p>\u201cO resultado dessa cultura sobrecarregada \u00e9 que felicidade e sucesso realmente parecem ser uma equa\u00e7\u00e3o de soma zero.\u00a0H\u00e1 um custo, geralmente humano, com o trabalho e a fam\u00edlia jogando cabo-de-guerra por tempo e aten\u00e7\u00e3o, e com felicidade pessoal sendo sempre sacrificada.\u00a0Isso era verdade muito antes da pandemia\u201d, destaca a professora.<\/p>\n<h5>Mais aten\u00e7\u00e3o \u00e0 felicidade nos tempos de crise<\/h5>\n<p>Segundo Nadejda, os estudos sobre a felicidade parecem se tornar mais populares durante os per\u00edodos de alto estresse social.\u00a0\u201cTalvez n\u00e3o seja coincid\u00eancia que o\u00a0<a href=\"https:\/\/news.harvard.edu\/gazette\/story\/2017\/04\/over-nearly-80-years-harvard-study-has-been-showing-how-to-live-a-healthy-and-happy-life\/\">estudo mais antigo sobre a felicidade<\/a>, administrado pela Universidade de Harvard, tenha se originado durante a Grande Depress\u00e3o.\u00a0Em 1938, os pesquisadores mediram a sa\u00fade f\u00edsica e mental de 268 alunos do segundo ano e, durante 80 anos, acompanharam esses homens e alguns de seus descendentes\u201d, ela conta.<\/p>\n<p>De acordo com a acad\u00eamica, os resultados revelaram que relacionamentos pr\u00f3ximos, mais do que dinheiro ou fama, mant\u00eam as pessoas felizes por toda a vida. \u201cIsso inclui um casamento e uma fam\u00edlia felizes e uma comunidade pr\u00f3xima de amigos que o apoiam.\u00a0\u00c9 importante ressaltar que os relacionamentos destacados no estudo s\u00e3o aqueles baseados no amor, cuidado e igualdade, ao inv\u00e9s de abuso e explora\u00e7\u00e3o\u201d, explica.<\/p>\n<p>A professora observa que, assim como a Grande Depress\u00e3o motivou o estudo de Harvard, a atual pandemia inspirou o cientista social Arthur Brooks a lan\u00e7ar, em abril de 2020, uma coluna semanal sobre felicidade intitulada <a href=\"https:\/\/www.theatlantic.com\/family\/archive\/2020\/04\/how-increase-happiness-according-research\/609619\/\">How to Build a Life<\/a>\u00a0(Como Construir uma Vida).\u00a0\u201cEm seu primeiro artigo para a s\u00e9rie, Brooks faz pesquisas mostrando que f\u00e9 e trabalho significativo, al\u00e9m de relacionamentos pr\u00f3ximos, podem aumentar a felicidade.<\/p>\n<h5><strong>Feliz mesmo no caos e na desordem<\/strong><\/h5>\n<p>De acordo com Nadejda, o conselho de Brooks se correlaciona com as descobertas no\u00a0Relat\u00f3rio Mundial de Felicidade de 2021 , que observou <em>um aumento de cerca de 10% no n\u00famero de pessoas que disseram estar preocupadas ou tristes no dia anterior<\/em>. \u201cF\u00e9, relacionamentos e trabalho significativo contribuem para a sensa\u00e7\u00e3o de seguran\u00e7a e estabilidade. Todos eles foram v\u00edtimas da pandemia. O padeiro de Pompeia, que escolheu colocar a placa em seu local de trabalho, provavelmente teria concordado sobre a conex\u00e3o significativa entre felicidade, trabalho e f\u00e9. E, embora ele n\u00e3o estivesse, pelo que os historiadores podem dizer, passando por uma pandemia, ele n\u00e3o era estranho ao estresse social\u201d, considera.<\/p>\n<p>Para a professora, \u00e9 poss\u00edvel que a escolha da inscri\u00e7\u00e3o refletisse uma corrente de ansiedade que \u00e9 compreens\u00edvel, tendo em vista a turbul\u00eancia pol\u00edtica em Pomp\u00e9ia e no\u00a0<a href=\"https:\/\/www.worldhistory.org\/article\/1724\/the-year-of-the-four-emperors--the-demise-of-four\/\">imp\u00e9rio em geral<\/a> nos \u00faltimos 20 anos de exist\u00eancia da cidade. \u201cNa \u00e9poca da erup\u00e7\u00e3o vulc\u00e2nica, sabemos que alguns pompeianos ainda estavam reconstruindo e restaurando os danos do <a href=\"https:\/\/politicsofdisaster.wordpress.com\/0790\/06\/09\/62-a-d-pompeii-earthquake-and-79-a-d-eruption-of-mt-vesuvius\/\">terremoto de 62 dC<\/a>\u00a0.\u00a0A vida do padeiro deve ter sido repleta de lembretes de instabilidade e desastre iminente.\u00a0Talvez a placa tenha sido uma tentativa de combater esses medos\u201d, acredita.<\/p>\n<h5>Sonhos e aspira\u00e7\u00f5es<\/h5>\n<p>Diante disso, Nadedja julga interessante questionar se as pessoas verdadeiramente felizes sentiriam a necessidade de colocar uma placa proclamando a presen\u00e7a da felicidade em seu lar. \u201cOu talvez eu esteja analisando demais este objeto, e era simplesmente uma bugiganga feita em massa. Uma vers\u00e3o do primeiro s\u00e9culo de um cartaz de \u2018Lar Doce Lar\u2019 ou \u2018Viva, Ria, Ame\u2019, que o padeiro ou sua esposa pegaram em um capricho\u201d, ela brinca.<\/p>\n<p>De qualquer forma, a inscri\u00e7\u00e3o lembra uma verdade importante: as pessoas na antiguidade tinham sonhos e aspira\u00e7\u00f5es \u00e0 felicidade, assim como temos hoje. \u201cO Ves\u00favio pode ter acabado com os sonhos de nosso padeiro, mas a pandemia n\u00e3o precisa ter um impacto t\u00e3o permanente sobre os nossos. E, embora o estresse do \u00faltimo ano e meio possa parecer insuport\u00e1vel, n\u00e3o houve melhor momento para reavaliar as prioridades e lembrar de colocar as pessoas e os relacionamentos em primeiro lugar\u201d, sugere Nadedja.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A felicidade humana \u00e9 notadamente resistente. Esta foi uma das principais li\u00e7\u00f5es que os pesquisadores respons\u00e1veis pela elabora\u00e7\u00e3o do Relat\u00f3rio<\/p>\n","protected":false},"author":1,"featured_media":2507,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/comments?post=2506"}],"version-history":[{"count":3,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2506\/revisions"}],"predecessor-version":[{"id":2509,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2506\/revisions\/2509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/media\/2507"}],"wp:attachment":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/media?parent=2506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/categories?post=2506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/tags?post=2506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}