{"id":2523,"date":"2021-09-24T12:54:47","date_gmt":"2021-09-24T15:54:47","guid":{"rendered":"https:\/\/www.comunidadeativa.jor.br\/?p=2523"},"modified":"2023-08-11T19:17:02","modified_gmt":"2023-08-11T22:17:02","slug":"momento-de-retomada-da-economia-cria-oportunidade-para-melhorar-as-relacoes-com-os-clientes","status":"publish","type":"post","link":"https:\/\/www.comunidadeativa.jor.br\/index.php\/2021\/09\/24\/momento-de-retomada-da-economia-cria-oportunidade-para-melhorar-as-relacoes-com-os-clientes\/","title":{"rendered":"Momento de retomada da economia cria oportunidade para melhorar as rela\u00e7\u00f5es com os clientes"},"content":{"rendered":"<p>Na medida em que a vacina\u00e7\u00e3o avan\u00e7a e a pandemia parece recuar, o setor de com\u00e9rcio e de servi\u00e7os j\u00e1 d\u00e1 sinais de rea\u00e7\u00e3o. Com essa perspectiva de recupera\u00e7\u00e3o do tempo perdido, o clima entre os empres\u00e1rios tamb\u00e9m come\u00e7a a melhorar na capital e, ao que tudo indica, a perspectiva de bons resultados em curto prazo \u00e9 esperada por boa parte deles.<\/p>\n<p><a href=\"https:\/\/www.cdlbh.com.br\/imprensa\/cdl-bh-otimista-com-o-segundo-semestre\/\" target=\"_blank\" rel=\"noopener\">De acordo com a C\u00e2mara de Dirigentes de Belo Horizonte (CDL\/BH)<\/a>, no primeiro semestre de 2021, o setor varejista registrou alta de 4,63% no volume de vendas, na compara\u00e7\u00e3o com o mesmo per\u00edodo de 2020. Com esse resultado, um levantamento realizado pela institui\u00e7\u00e3o aponta que o<a href=\"https:\/\/www.comunidadeativa.jor.br\/index.php\/2021\/07\/26\/cdl-bh-tem-boa-expectativa-para-o-setor-de-comercio-e-de-servicos-da-capital-no-segundo-semestre\/\" target=\"_blank\" rel=\"noopener\"> indicador de confian\u00e7a do empresariados<\/a> belo-horizontino fechou o segundo trimestre do ano em 55,3 pontos, contra 40,1 pontos do trimestre anterior, em uma escala em que zero sinaliza a pior confian\u00e7a e 100 a m\u00e1xima.<\/p>\n<p>A expectativa da CDL\/BH \u00e9 de que, com a chegada das datas comemorativas de final de ano, o quadro se torne ainda mais promissor. Entretanto, para que o sucesso dos neg\u00f3cios retorne aos n\u00edveis desejados, n\u00e3o basta contar com o as boas perspectivas. O empresariado tamb\u00e9m deve agir de acordo com as exig\u00eancias do mercado, que, mais do que em qualquer \u00e9poca, exige uma valoriza\u00e7\u00e3o ainda maior do cliente.<\/p>\n<h5>Entendendo o cliente<\/h5>\n<p>As grandes empresas se dedicam o tempo todo a conhecerem as caracter\u00edsticas dos consumidores que atendem. Pra isso, grande parte investe pesado em pesquisas de mercado, o que n\u00e3o \u00e9 acess\u00edvel para o pequeno empreendedor, considerando que esse tipo de estrat\u00e9gia tem um custo significativo.<\/p>\n<p>Por\u00e9m, mesmo o empres\u00e1rio de menor porte pode adotar medidas que o levem a compreender melhor o p\u00fablico que atende. O pr\u00f3prio relacionamento di\u00e1rio \u201cde balc\u00e3o\u201d, enquetes pelas redes sociais e a observa\u00e7\u00e3o do comportamento do cliente nas recusas e na aprova\u00e7\u00e3o de produtos e de servi\u00e7os ajudam bastante a entend\u00ea-lo melhor.<\/p>\n<p>N\u00e3o custa nada fazer uma pesquisa de satisfa\u00e7\u00e3o personalizada. Pra isso, basta entrar em contato com o cliente para perguntar sobre o que ele achou do atendimento, do produto ou do servi\u00e7o, das instala\u00e7\u00f5es e de outros aspectos que possam ser relevantes para a experi\u00eancia dele como consumidor.<\/p>\n<p>Ali\u00e1s, a chamada \u201cexperi\u00eancia do cliente\u201d, conceito que anda t\u00e3o falado ultimamente, \u00e9 um fator que precisa ser valorizado de forma intensa nos dias de hoje.<\/p>\n<h5>A experi\u00eancia do cliente<\/h5>\n<p>Entende-se por <em>experi\u00eancia do cliente<\/em> o conjunto de intera\u00e7\u00f5es que ele experimenta ao longo de todo o per\u00edodo em que ele tem contato com uma empresa. Durante esse tempo, o cliente passa por uma etapa daquilo que os especialistas em marketing denominam como a <em>jornada do consumidor<\/em>, que come\u00e7a antes mesmo de ele entrar em contato com um estabelecimento para atender \u00e0 sua necessidade.<\/p>\n<p>Essa tal jornada inicia quando o consumidor descobre que tem uma demanda que precisa ser suprida e, em seguida, come\u00e7a a buscar as poss\u00edveis solu\u00e7\u00f5es. O final da jornada ocorre quando ele se decide pela compra.<\/p>\n<p>Nessa trajet\u00f3ria, quando o consumidor se torna cliente de uma empresa ele inicia a sua experi\u00eancia com aquele estabelecimento, que pode ser positiva ou negativa, dependendo da forma como aquele conjunto de intera\u00e7\u00f5es acontecer\u00e1.<\/p>\n<p>Vale considerar que essa experi\u00eancia n\u00e3o termina ap\u00f3s a jornada do consumidor. Ao contr\u00e1rio, ele se estende para al\u00e9m e pode ser positiva ou negativa, o que vai depender da qualidade do que foi entregue e da forma como as rela\u00e7\u00f5es aconteceram.<\/p>\n<p>Fato \u00e9 que se a intera\u00e7\u00e3o for positiva \u00e9 bastante poss\u00edvel que aquele consumidor retorne e at\u00e9 se transforme em um divulgador da marca. Se for negativa, \u00e9 claro, o efeito tende a ser o oposto.<\/p>\n<h5>Medida certa<\/h5>\n<p>Proporcionar uma boa experi\u00eancia requer a\u00e7\u00f5es na medida certa, que eliminem o risco de serem confundidas com lisonjas excessivas e inconvenientes. Em vez disso, \u00e9 preciso desenvolver a empatia com o cliente a ponto de entend\u00ea-lo na maneira de pensar e de agir.<\/p>\n<p>Pra isso, \u00e9 conveniente fazer um r\u00e1pido levantamento sobre as reais necessidades que ele tem e o que o levou a buscar aquele determinado estabelecimento. Em uma breve conversa no primeiro contato, sem grandes formalidades, mas com real interesse, \u00e9 poss\u00edvel entender de maneira satisfat\u00f3ria as origens da demanda.<\/p>\n<p>Da mesma forma, ap\u00f3s o atendimento, com um simples telefonema ou enviando uma mensagem pelo WhatsApp, fica f\u00e1cil descobrir quais foram os resultados de satisfa\u00e7\u00e3o, tanto com o produto ou com o servi\u00e7o quanto com a pr\u00f3pria experi\u00eancia de consumo.<\/p>\n<h5>Saber ouvir<\/h5>\n<p>Um p\u00e9ssimo h\u00e1bito que ainda se mant\u00e9m em muitas empresas est\u00e1 na resist\u00eancia em receber cr\u00edticas. Entretanto, no momento em que recebe o retorno do cliente, se o empres\u00e1rio compreende que aquilo que ele fala, na maioria das vezes, \u00e9 o reflexo da experi\u00eancia que teve durante a experi\u00eancia de consumo, ser\u00e1 poss\u00edvel identificar os pontos negativos e, assim, corrigi-los.<\/p>\n<p>Diferente da antiga m\u00e1xima que diz que o \u201ccliente tem sempre raz\u00e3o\u201d, saber receber cr\u00edticas n\u00e3o significa concordar at\u00e9 com os pontos irracionais que o clientela apresenta. Apenas, diz respeito \u00e0 disposi\u00e7\u00e3o em ouvi-la de forma atenta e interessada e, na medida da identifica\u00e7\u00e3o de problemas, na busca por solucion\u00e1-los.<\/p>\n<h5>Facilidade de comunica\u00e7\u00e3o<\/h5>\n<p>Por fim, outro aspecto que precisa ser valorizado est\u00e1 na facilidade de comunica\u00e7\u00e3o do cliente com a empresa. De fato, h\u00e1 ocorr\u00eancias de comunica\u00e7\u00e3o extremamente frustrantes \u2014 e p\u00e9ssimas para a experi\u00eancia de consumo \u2014 que precisam ser evitadas.\u00a0A demora no atendimento, falta de resposta a solicita\u00e7\u00f5es de informa\u00e7\u00f5es ou a reclama\u00e7\u00f5es e a impessoalidade e frieza, por exemplo, desestimulam o consumo e dificultam o relacionamento com o consumidor.<\/p>\n<p>Para aproveitar bem esse momento de retomada do consumo \u00e9 indispens\u00e1vel que as empresas se preparem para valorizar e para entenderem cada vez mais o p\u00fablico que atendem. Assim, considerando que h\u00e1 uma vontade de consumir reprimida, al\u00e9m da recupera\u00e7\u00e3o do neg\u00f3cio, essa tamb\u00e9m \u00e9 uma oportunidade para que as empresas estabele\u00e7am rela\u00e7\u00f5es mais proveitosas e duradouras com seus clientes.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na medida em que a vacina\u00e7\u00e3o avan\u00e7a e a pandemia parece recuar, o setor de com\u00e9rcio e de servi\u00e7os j\u00e1<\/p>\n","protected":false},"author":1,"featured_media":2524,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidadania"],"_links":{"self":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/comments?post=2523"}],"version-history":[{"count":4,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2523\/revisions"}],"predecessor-version":[{"id":3920,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/2523\/revisions\/3920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/media\/2524"}],"wp:attachment":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/media?parent=2523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/categories?post=2523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/tags?post=2523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}