{"id":4838,"date":"2025-06-04T12:11:49","date_gmt":"2025-06-04T15:11:49","guid":{"rendered":"https:\/\/www.comunidadeativa.jor.br\/?p=4838"},"modified":"2025-06-04T15:59:35","modified_gmt":"2025-06-04T18:59:35","slug":"federalizacao-da-uemg-deixa-comunidade-academica-apreensiva","status":"publish","type":"post","link":"https:\/\/www.comunidadeativa.jor.br\/index.php\/2025\/06\/04\/federalizacao-da-uemg-deixa-comunidade-academica-apreensiva\/","title":{"rendered":"Federaliza\u00e7\u00e3o da Uemg deixa comunidade acad\u00eamica apreensiva"},"content":{"rendered":"<p>Em tramita\u00e7\u00e3o na Assembleia Legislativa de Minas Gerais (ALMG), o Projeto de Lei (PL) n\u00ba 3.738\/2025 pretende autorizar o Executivo estadual a transferir para a Uni\u00e3o a gest\u00e3o da Universidade do Estado de Minas Gerais (Uemg), e tamb\u00e9m a propriedade dos bens m\u00f3veis e im\u00f3veis da institui\u00e7\u00e3o. De autoria do governo de Minas, o PL faz parte de um pacote de medidas destinadas a reduzir a d\u00edvida mineira com os cofres federais, que, em maio, ultrapassou a casa dos R$ 167 bilh\u00f5es. O valor total dos im\u00f3veis da Uemg est\u00e1 estimado em R$ 500 milh\u00f5es, o que representa menos de 0,3% do d\u00e9bito total.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4848\" aria-describedby=\"caption-attachment-4848\" style=\"width: 553px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-4848\" src=\"http:\/\/www.comunidadeativa.jor.br\/wp-content\/uploads\/2025\/06\/CAPA102.png\" alt=\"\" width=\"553\" height=\"308\" srcset=\"https:\/\/www.comunidadeativa.jor.br\/wp-content\/uploads\/2025\/06\/CAPA102.png 800w, https:\/\/www.comunidadeativa.jor.br\/wp-content\/uploads\/2025\/06\/CAPA102-300x167.png 300w, https:\/\/www.comunidadeativa.jor.br\/wp-content\/uploads\/2025\/06\/CAPA102-768x427.png 768w\" sizes=\"auto, (max-width: 553px) 100vw, 553px\" \/><figcaption id=\"caption-attachment-4848\" class=\"wp-caption-text\">A sede da Escola Guignard, no Comiteco, faz parte do conjunto de im\u00f3veis da Uemg que pode ser transferido para a Uni\u00e3o \u2014 Foto: Andr\u00e9VRuas\/Wikimedia<\/figcaption><\/figure>\n<p>Contudo, mesmo valendo uma parte pequena do montante devido por Minas \u00e0 Uni\u00e3o, para os servidores, alunos e professores da Uemg, a transfer\u00eancia tem potencial para causar um impacto negativo consider\u00e1vel. Temendo pelo futuro da universidade, funcion\u00e1rios, discentes e docentes da institui\u00e7\u00e3o est\u00e3o compartilhando nas redes sociais um manifesto que \u00e9 taxativo quanto \u00e0s consequ\u00eancias do PL, afirmando que existem riscos reais para o patrim\u00f4nio do povo mineiro. \u201cCursos podem ser extintos, estruturas desmontadas e cidades podem ser deixadas sem acesso ao ensino superior p\u00fablico. E o mais grave: tudo est\u00e1 sendo feito sem ouvir a comunidade acad\u00eamica, sem transpar\u00eancia e sem compromisso com o futuro da educa\u00e7\u00e3o mineira\u201d, diz a mensagem.<\/p>\n<h5>Acesso ao ensino<\/h5>\n<p>Fundada em 1989, a Uemg est\u00e1 presente em 19 munic\u00edpios mineiros, atendendo a mais de 21 mil estudantes, a partir de 22 unidades acad\u00eamicas. A institui\u00e7\u00e3o oferece mais de 60 cursos de gradua\u00e7\u00e3o em v\u00e1rias \u00e1reas, que incluem Medicina, Engenharia, M\u00fasica e Artes Pl\u00e1sticas, cuja faculdade fica no bairro Comiteco. Ainda, oferta cursos de p\u00f3s-gradua\u00e7\u00e3o e \u00e9 base para importantes projetos de pesquisa no Estado. O temor no meio acad\u00eamico se deve \u00e0 possibilidade de a transfer\u00eancia da institui\u00e7\u00e3o para o \u00e2mbito federal prejudicar toda essa atividade.<\/p>\n<p>Em entrevista \u00e0 Band Minas, Cristina Fonseca, diretora executiva da Associa\u00e7\u00e3o dos Docentes da Universidade do Estado de Minas Gerais (Aduemg), manifestou a preocupa\u00e7\u00e3o. \u201cO governo do estado est\u00e1 oferecendo os bens m\u00f3veis e im\u00f3veis. N\u00e3o est\u00e1 oferecendo a Universidade como um todo\u201d, disse Cristina.<\/p>\n<p>A diretora destacou ainda a irregularidade da transfer\u00eancia. \u201cA federaliza\u00e7\u00e3o \u00e9 inconstitucional. N\u00e3o existe federaliza\u00e7\u00e3o de servidores p\u00fablicos estaduais. N\u00e3o existe federaliza\u00e7\u00e3o da Uemg\u201d, alertou.<\/p>\n<p>Para ter acesso ao PL 3.738 e para manifestar a sua opini\u00e3o sobre o assunto, <a href=\"https:\/\/www.almg.gov.br\/painel\/15403\">clique aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em tramita\u00e7\u00e3o na Assembleia Legislativa de Minas Gerais (ALMG), o Projeto de Lei (PL) n\u00ba 3.738\/2025 pretende autorizar o Executivo<\/p>\n","protected":false},"author":1,"featured_media":4848,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-4838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"_links":{"self":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/4838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/comments?post=4838"}],"version-history":[{"count":5,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/4838\/revisions"}],"predecessor-version":[{"id":4851,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/posts\/4838\/revisions\/4851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/media\/4848"}],"wp:attachment":[{"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/media?parent=4838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/categories?post=4838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunidadeativa.jor.br\/index.php\/wp-json\/wp\/v2\/tags?post=4838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}